{"id":1894,"count":1,"description":"","link":"http:\/\/golfstinks.com\/blog\/tag\/stogie","name":"stogie","slug":"stogie","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>stogie Archives &#8226; GolfStinks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/golfstinks.com\/blog\/tag\/stogie\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"stogie Archives &#8226; GolfStinks\" \/>\n<meta property=\"og:url\" content=\"https:\/\/golfstinks.com\/blog\/tag\/stogie\" \/>\n<meta property=\"og:site_name\" content=\"GolfStinks\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@golfstinks\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/golfstinks.com\\\/blog\\\/tag\\\/stogie\",\"url\":\"https:\\\/\\\/golfstinks.com\\\/blog\\\/tag\\\/stogie\",\"name\":\"stogie Archives &#8226; GolfStinks\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/golfstinks.com\\\/blog\\\/tag\\\/stogie#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/golfstinks.com\\\/blog\\\/tag\\\/stogie#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/golfstinks.com\\\/blog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"stogie\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/#website\",\"url\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/\",\"name\":\"GolfStinks\",\"description\":\"A Golf Blog for the Rest of Us!\",\"publisher\":{\"@id\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/#organization\",\"name\":\"Golfstinks, LLC\",\"url\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/GolfStinks-logo-RGB.png\",\"contentUrl\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/GolfStinks-logo-RGB.png\",\"width\":700,\"height\":578,\"caption\":\"Golfstinks, LLC\"},\"image\":{\"@id\":\"http:\\\/\\\/golfstinks.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/golfstinks\",\"https:\\\/\\\/x.com\\\/golfstinks\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/golfstinks-llc\",\"http:\\\/\\\/pinterest.com\\\/golfstinks\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/golfstinksvideo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"stogie Archives &#8226; GolfStinks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/golfstinks.com\/blog\/tag\/stogie","og_locale":"en_US","og_type":"article","og_title":"stogie Archives &#8226; GolfStinks","og_url":"https:\/\/golfstinks.com\/blog\/tag\/stogie","og_site_name":"GolfStinks","twitter_card":"summary_large_image","twitter_site":"@golfstinks","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/golfstinks.com\/blog\/tag\/stogie","url":"https:\/\/golfstinks.com\/blog\/tag\/stogie","name":"stogie Archives &#8226; GolfStinks","isPartOf":{"@id":"http:\/\/golfstinks.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/golfstinks.com\/blog\/tag\/stogie#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/golfstinks.com\/blog\/tag\/stogie#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/golfstinks.com\/blog"},{"@type":"ListItem","position":2,"name":"stogie"}]},{"@type":"WebSite","@id":"http:\/\/golfstinks.com\/blog\/#website","url":"http:\/\/golfstinks.com\/blog\/","name":"GolfStinks","description":"A Golf Blog for the Rest of Us!","publisher":{"@id":"http:\/\/golfstinks.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/golfstinks.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/golfstinks.com\/blog\/#organization","name":"Golfstinks, LLC","url":"http:\/\/golfstinks.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/golfstinks.com\/blog\/#\/schema\/logo\/image\/","url":"http:\/\/golfstinks.com\/blog\/wp-content\/uploads\/2017\/03\/GolfStinks-logo-RGB.png","contentUrl":"http:\/\/golfstinks.com\/blog\/wp-content\/uploads\/2017\/03\/GolfStinks-logo-RGB.png","width":700,"height":578,"caption":"Golfstinks, LLC"},"image":{"@id":"http:\/\/golfstinks.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/golfstinks","https:\/\/x.com\/golfstinks","https:\/\/www.linkedin.com\/company\/golfstinks-llc","http:\/\/pinterest.com\/golfstinks","https:\/\/www.youtube.com\/user\/golfstinksvideo"]}]}},"_links":{"self":[{"href":"http:\/\/golfstinks.com\/blog\/wp-json\/wp\/v2\/tags\/1894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/golfstinks.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/golfstinks.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/golfstinks.com\/blog\/wp-json\/wp\/v2\/posts?tags=1894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}